{"id":53860,"date":"2026-05-13T12:05:38","date_gmt":"2026-05-13T09:05:38","guid":{"rendered":"https:\/\/fyi.news\/?post_type=articles&#038;p=53860"},"modified":"2026-05-13T12:13:00","modified_gmt":"2026-05-13T09:13:00","slug":"ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall","status":"publish","type":"articles","link":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/","title":{"rendered":"Ilioupoli: One dead, 17-year-old in critical condition after fall"},"excerpt":{"rendered":"","protected":false},"featured_media":53859,"template":"","article_categories":[29],"article_tags":[],"class_list":["post-53860","articles","type-articles","status-publish","has-post-thumbnail","hentry","article_categories-news-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ilioupoli: One dead, 17-year-old in critical condition after fall - FYI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ilioupoli: One dead, 17-year-old in critical condition after fall - FYI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/\" \/>\n<meta property=\"og:site_name\" content=\"FYI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fyi.news.official\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T09:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fyi.news\/wp-content\/uploads\/2026\/05\/6430216-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/\",\"url\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/\",\"name\":\"Ilioupoli: One dead, 17-year-old in critical condition after fall - FYI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fyi.news\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6430216-scaled.jpg\",\"datePublished\":\"2026-05-13T09:05:38+00:00\",\"dateModified\":\"2026-05-13T09:13:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fyi.news\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6430216-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/fyi.news\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/6430216-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"\u0395\u039b\u039b\u0397\u039d\u0399\u039a\u0397 \u0391\u03a3\u03a4\u03a5\u039d\u039f\u039c\u0399\u0391. \u03a0\u03b1\u03c1\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae 10 \u0399\u03b1\u03bd\u03bf\u03c5\u03b1\u03c1\u03af\u03bf\u03c5 2025 (\u0393\u0399\u03a9\u03a1\u0393\u039f\u03a3 \u039a\u039f\u039d\u03a4\u0391\u03a1\u0399\u039d\u0397\u03a3\\\/EUROKINISSI)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fyi.news\\\/en\\\/articles\\\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fyi.news\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/categories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ilioupoli: One dead, 17-year-old in critical condition after fall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/\",\"name\":\"FYI News\",\"description\":\"\u03b5\u03b9\u03b4\u03ae\u03c3\u03b5\u03b9\u03c2 \u03b3\u03b9\u03b1 \u03c3\u03ad\u03bd\u03b1\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/#organization\",\"name\":\"FYI News\",\"url\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fyi.news\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo_fyi.svg\",\"contentUrl\":\"https:\\\/\\\/fyi.news\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo_fyi.svg\",\"width\":75,\"height\":53,\"caption\":\"FYI News\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fyi.news\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fyi.news.official\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ilioupoli: One dead, 17-year-old in critical condition after fall - FYI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/","og_locale":"en_US","og_type":"article","og_title":"Ilioupoli: One dead, 17-year-old in critical condition after fall - FYI","og_url":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/","og_site_name":"FYI","article_publisher":"https:\/\/www.facebook.com\/fyi.news.official","article_modified_time":"2026-05-13T09:13:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/fyi.news\/wp-content\/uploads\/2026\/05\/6430216-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/","url":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/","name":"Ilioupoli: One dead, 17-year-old in critical condition after fall - FYI","isPartOf":{"@id":"https:\/\/www.fyi.news\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/#primaryimage"},"image":{"@id":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/#primaryimage"},"thumbnailUrl":"https:\/\/fyi.news\/wp-content\/uploads\/2026\/05\/6430216-scaled.jpg","datePublished":"2026-05-13T09:05:38+00:00","dateModified":"2026-05-13T09:13:00+00:00","breadcrumb":{"@id":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/#primaryimage","url":"https:\/\/fyi.news\/wp-content\/uploads\/2026\/05\/6430216-scaled.jpg","contentUrl":"https:\/\/fyi.news\/wp-content\/uploads\/2026\/05\/6430216-scaled.jpg","width":2560,"height":1920,"caption":"\u0395\u039b\u039b\u0397\u039d\u0399\u039a\u0397 \u0391\u03a3\u03a4\u03a5\u039d\u039f\u039c\u0399\u0391. \u03a0\u03b1\u03c1\u03b1\u03c3\u03ba\u03b5\u03c5\u03ae 10 \u0399\u03b1\u03bd\u03bf\u03c5\u03b1\u03c1\u03af\u03bf\u03c5 2025 (\u0393\u0399\u03a9\u03a1\u0393\u039f\u03a3 \u039a\u039f\u039d\u03a4\u0391\u03a1\u0399\u039d\u0397\u03a3\/EUROKINISSI)"},{"@type":"BreadcrumbList","@id":"https:\/\/fyi.news\/en\/articles\/ilioupoli-one-dead-17-year-old-in-critical-condition-after-fall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fyi.news\/en\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/www.fyi.news\/en\/categories\/"},{"@type":"ListItem","position":3,"name":"Ilioupoli: One dead, 17-year-old in critical condition after fall"}]},{"@type":"WebSite","@id":"https:\/\/www.fyi.news\/en\/#website","url":"https:\/\/www.fyi.news\/en\/","name":"FYI News","description":"\u03b5\u03b9\u03b4\u03ae\u03c3\u03b5\u03b9\u03c2 \u03b3\u03b9\u03b1 \u03c3\u03ad\u03bd\u03b1","publisher":{"@id":"https:\/\/www.fyi.news\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fyi.news\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fyi.news\/en\/#organization","name":"FYI News","url":"https:\/\/www.fyi.news\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fyi.news\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fyi.news\/wp-content\/uploads\/2023\/03\/Logo_fyi.svg","contentUrl":"https:\/\/fyi.news\/wp-content\/uploads\/2023\/03\/Logo_fyi.svg","width":75,"height":53,"caption":"FYI News"},"image":{"@id":"https:\/\/www.fyi.news\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fyi.news.official"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"FYI","distributor_original_site_url":"https:\/\/fyi.news\/en\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/articles\/53860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/types\/articles"}],"version-history":[{"count":1,"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/articles\/53860\/revisions"}],"predecessor-version":[{"id":53861,"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/articles\/53860\/revisions\/53861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/media\/53859"}],"wp:attachment":[{"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/media?parent=53860"}],"wp:term":[{"taxonomy":"article_categories","embeddable":true,"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/article_categories?post=53860"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/fyi.news\/en\/wp-json\/wp\/v2\/article_tags?post=53860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}